{"id":53071,"date":"2026-05-12T07:25:09","date_gmt":"2026-05-12T07:25:09","guid":{"rendered":"https:\/\/www.navarrafilmindustry.com\/empresas-profesionales\/borja-elizalde-beruete\/"},"modified":"2026-05-12T11:35:34","modified_gmt":"2026-05-12T11:35:34","slug":"borja-elizalde-beruete","status":"publish","type":"empresa-profesional","link":"https:\/\/www.navarrafilmindustry.com\/eu\/empresas-profesionales\/borja-elizalde-beruete\/","title":{"rendered":"Borja Elizalde Beruete"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":52654,"parent":0,"template":"","class_list":{"0":"post-53071","1":"empresa-profesional","2":"type-empresa-profesional","3":"status-publish","4":"has-post-thumbnail","6":"categoria-produkzioko-laguntzailea","7":"categoria-figurantea","8":"categoria-auxiliar-de-produccion","9":"categoria-figurante","10":"empresa-profesional-tipo-profesionala"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Borja Elizalde Beruete - NFI<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.navarrafilmindustry.com\/es\/empresas-profesionales\/borja-elizalde-beruete\/\" \/>\n<meta property=\"og:locale\" content=\"eu_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Borja Elizalde Beruete - NFI\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.navarrafilmindustry.com\/es\/empresas-profesionales\/borja-elizalde-beruete\/\" \/>\n<meta property=\"og:site_name\" content=\"NFI\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T11:35:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.navarrafilmindustry.com\/wp-content\/uploads\/2026\/04\/52646-Borja-Elizalde-Beruete-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1709\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.navarrafilmindustry.com\/es\/empresas-profesionales\/borja-elizalde-beruete\/\",\"url\":\"https:\/\/www.navarrafilmindustry.com\/es\/empresas-profesionales\/borja-elizalde-beruete\/\",\"name\":\"Borja Elizalde Beruete - NFI\",\"isPartOf\":{\"@id\":\"https:\/\/www.navarrafilmindustry.com\/eu\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.navarrafilmindustry.com\/es\/empresas-profesionales\/borja-elizalde-beruete\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.navarrafilmindustry.com\/es\/empresas-profesionales\/borja-elizalde-beruete\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.navarrafilmindustry.com\/wp-content\/uploads\/2026\/04\/52646-Borja-Elizalde-Beruete-scaled.jpg\",\"datePublished\":\"2026-05-12T07:25:09+00:00\",\"dateModified\":\"2026-05-12T11:35:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.navarrafilmindustry.com\/es\/empresas-profesionales\/borja-elizalde-beruete\/#breadcrumb\"},\"inLanguage\":\"eu-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.navarrafilmindustry.com\/es\/empresas-profesionales\/borja-elizalde-beruete\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\/\/www.navarrafilmindustry.com\/es\/empresas-profesionales\/borja-elizalde-beruete\/#primaryimage\",\"url\":\"https:\/\/www.navarrafilmindustry.com\/wp-content\/uploads\/2026\/04\/52646-Borja-Elizalde-Beruete-scaled.jpg\",\"contentUrl\":\"https:\/\/www.navarrafilmindustry.com\/wp-content\/uploads\/2026\/04\/52646-Borja-Elizalde-Beruete-scaled.jpg\",\"width\":1709,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.navarrafilmindustry.com\/es\/empresas-profesionales\/borja-elizalde-beruete\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.navarrafilmindustry.com\/eu\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Empresas y profesionales\",\"item\":\"https:\/\/www.navarrafilmindustry.com\/es\/empresas-profesionales\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Borja Elizalde Beruete\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.navarrafilmindustry.com\/eu\/#website\",\"url\":\"https:\/\/www.navarrafilmindustry.com\/eu\/\",\"name\":\"NFI\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.navarrafilmindustry.com\/eu\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu-ES\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Borja Elizalde Beruete - NFI","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.navarrafilmindustry.com\/es\/empresas-profesionales\/borja-elizalde-beruete\/","og_locale":"eu_ES","og_type":"article","og_title":"Borja Elizalde Beruete - NFI","og_url":"https:\/\/www.navarrafilmindustry.com\/es\/empresas-profesionales\/borja-elizalde-beruete\/","og_site_name":"NFI","article_modified_time":"2026-05-12T11:35:34+00:00","og_image":[{"width":1709,"height":2560,"url":"https:\/\/www.navarrafilmindustry.com\/wp-content\/uploads\/2026\/04\/52646-Borja-Elizalde-Beruete-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.navarrafilmindustry.com\/es\/empresas-profesionales\/borja-elizalde-beruete\/","url":"https:\/\/www.navarrafilmindustry.com\/es\/empresas-profesionales\/borja-elizalde-beruete\/","name":"Borja Elizalde Beruete - NFI","isPartOf":{"@id":"https:\/\/www.navarrafilmindustry.com\/eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.navarrafilmindustry.com\/es\/empresas-profesionales\/borja-elizalde-beruete\/#primaryimage"},"image":{"@id":"https:\/\/www.navarrafilmindustry.com\/es\/empresas-profesionales\/borja-elizalde-beruete\/#primaryimage"},"thumbnailUrl":"https:\/\/www.navarrafilmindustry.com\/wp-content\/uploads\/2026\/04\/52646-Borja-Elizalde-Beruete-scaled.jpg","datePublished":"2026-05-12T07:25:09+00:00","dateModified":"2026-05-12T11:35:34+00:00","breadcrumb":{"@id":"https:\/\/www.navarrafilmindustry.com\/es\/empresas-profesionales\/borja-elizalde-beruete\/#breadcrumb"},"inLanguage":"eu-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.navarrafilmindustry.com\/es\/empresas-profesionales\/borja-elizalde-beruete\/"]}]},{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/www.navarrafilmindustry.com\/es\/empresas-profesionales\/borja-elizalde-beruete\/#primaryimage","url":"https:\/\/www.navarrafilmindustry.com\/wp-content\/uploads\/2026\/04\/52646-Borja-Elizalde-Beruete-scaled.jpg","contentUrl":"https:\/\/www.navarrafilmindustry.com\/wp-content\/uploads\/2026\/04\/52646-Borja-Elizalde-Beruete-scaled.jpg","width":1709,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/www.navarrafilmindustry.com\/es\/empresas-profesionales\/borja-elizalde-beruete\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.navarrafilmindustry.com\/eu\/"},{"@type":"ListItem","position":2,"name":"Empresas y profesionales","item":"https:\/\/www.navarrafilmindustry.com\/es\/empresas-profesionales\/"},{"@type":"ListItem","position":3,"name":"Borja Elizalde Beruete"}]},{"@type":"WebSite","@id":"https:\/\/www.navarrafilmindustry.com\/eu\/#website","url":"https:\/\/www.navarrafilmindustry.com\/eu\/","name":"NFI","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.navarrafilmindustry.com\/eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu-ES"}]}},"_links":{"self":[{"href":"https:\/\/www.navarrafilmindustry.com\/eu\/wp-json\/wp\/v2\/empresa-profesional\/53071"}],"collection":[{"href":"https:\/\/www.navarrafilmindustry.com\/eu\/wp-json\/wp\/v2\/empresa-profesional"}],"about":[{"href":"https:\/\/www.navarrafilmindustry.com\/eu\/wp-json\/wp\/v2\/types\/empresa-profesional"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.navarrafilmindustry.com\/eu\/wp-json\/wp\/v2\/media\/52654"}],"wp:attachment":[{"href":"https:\/\/www.navarrafilmindustry.com\/eu\/wp-json\/wp\/v2\/media?parent=53071"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}