{"id":39246,"date":"2024-04-17T12:04:11","date_gmt":"2024-04-17T12:04:11","guid":{"rendered":"https:\/\/www.navarrafilmindustry.com\/?post_type=empresa-profesional&#038;p=39246"},"modified":"2026-01-19T11:43:41","modified_gmt":"2026-01-19T11:43:41","slug":"global-servicios-culturales","status":"publish","type":"empresa-profesional","link":"https:\/\/www.navarrafilmindustry.com\/es\/empresas-profesionales\/global-servicios-culturales\/","title":{"rendered":"Global Servicios Culturales"},"content":{"rendered":"<p>Global Servicios Culturales cuenta con una plantilla fija de 17 t\u00e9cnicos especialistas en artes esc\u00e9nicas (sonido, iluminaci\u00f3n, maquinaria&#8230;), y un amplio abanico de personal auxiliar de carga y descarga, personal de atenci\u00f3n y profesional t\u00e9cnico especialista que habitualmente trabaja para nosotros. Desde Global se realiza la busqueda del perfil indicado, su alta en la seguridad social, nominas etc<\/p>\n<p>Global Servicios Culturales tambi\u00e9n cuenta con un departamento de gesti\u00f3n cultural desde el que se realizan las producci\u00f3n de diferentes eventos como exposiciones en Ciudadela, Festival de danza vertical, la muralla en danza desde su primera edici\u00f3n, Festival de Teatro de Olite&#8230; Para atender todos estos eventos Global hace la producci\u00f3n y asistencia t\u00e9cnica de cualquier evento desde el trabajo de oficina hasta el personal de atenci\u00f3n al p\u00fablico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Global Servicios Culturales cuenta con una plantilla fija de 17 t\u00e9cnicos especialistas en artes esc\u00e9nicas (sonido, iluminaci\u00f3n, maquinaria&#8230;), y un amplio abanico de personal auxiliar de carga y descarga, personal de atenci\u00f3n y profesional t\u00e9cnico especialista que habitualmente trabaja para nosotros. Desde Global se realiza la busqueda del perfil indicado, su alta en la seguridad social, nominas etc Global Servicios Culturales tambi\u00e9n cuenta con un departamento de gesti\u00f3n cultural desde el que se realizan las producci\u00f3n de diferentes eventos como exposiciones en Ciudadela, Festival de danza vertical, la muralla en danza desde su primera edici\u00f3n, Festival de Teatro de Olite&#8230; Para atender todos estos eventos Global hace la producci\u00f3n y asistencia t\u00e9cnica de cualquier evento desde el trabajo de oficina hasta el personal de atenci\u00f3n al p\u00fablico.<\/p>\n","protected":false},"featured_media":39247,"parent":0,"template":"","class_list":{"0":"post-39246","1":"empresa-profesional","2":"type-empresa-profesional","3":"status-publish","4":"has-post-thumbnail","6":"categoria-empresas","7":"categoria-contratacion-de-personal","8":"categoria-servicios","9":"empresa-profesional-tipo-empresa"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Global Servicios Culturales - NFI<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.navarrafilmindustry.com\/es\/empresas-profesionales\/global-servicios-culturales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Global Servicios Culturales - NFI\" \/>\n<meta property=\"og:description\" content=\"Global Servicios Culturales cuenta con una plantilla fija de 17 t\u00e9cnicos especialistas en artes esc\u00e9nicas (sonido, iluminaci\u00f3n, maquinaria&#8230;), y un amplio abanico de personal auxiliar de carga y descarga, personal de atenci\u00f3n y profesional t\u00e9cnico especialista que habitualmente trabaja para nosotros. Desde Global se realiza la busqueda del perfil indicado, su alta en la seguridad social, nominas etc Global Servicios Culturales tambi\u00e9n cuenta con un departamento de gesti\u00f3n cultural desde el que se realizan las producci\u00f3n de diferentes eventos como exposiciones en Ciudadela, Festival de danza vertical, la muralla en danza desde su primera edici\u00f3n, Festival de Teatro de Olite&#8230; Para atender todos estos eventos Global hace la producci\u00f3n y asistencia t\u00e9cnica de cualquier evento desde el trabajo de oficina hasta el personal de atenci\u00f3n al p\u00fablico.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.navarrafilmindustry.com\/es\/empresas-profesionales\/global-servicios-culturales\/\" \/>\n<meta property=\"og:site_name\" content=\"NFI\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-19T11:43:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.navarrafilmindustry.com\/wp-content\/uploads\/2024\/04\/39246-LoGlobal2010-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"504\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.navarrafilmindustry.com\/es\/empresas-profesionales\/global-servicios-culturales\/\",\"url\":\"https:\/\/www.navarrafilmindustry.com\/es\/empresas-profesionales\/global-servicios-culturales\/\",\"name\":\"Global Servicios Culturales - NFI\",\"isPartOf\":{\"@id\":\"https:\/\/www.navarrafilmindustry.com\/eu\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.navarrafilmindustry.com\/es\/empresas-profesionales\/global-servicios-culturales\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.navarrafilmindustry.com\/es\/empresas-profesionales\/global-servicios-culturales\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.navarrafilmindustry.com\/wp-content\/uploads\/2024\/04\/39246-LoGlobal2010-1.jpg\",\"datePublished\":\"2024-04-17T12:04:11+00:00\",\"dateModified\":\"2026-01-19T11:43:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.navarrafilmindustry.com\/es\/empresas-profesionales\/global-servicios-culturales\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.navarrafilmindustry.com\/es\/empresas-profesionales\/global-servicios-culturales\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.navarrafilmindustry.com\/es\/empresas-profesionales\/global-servicios-culturales\/#primaryimage\",\"url\":\"https:\/\/www.navarrafilmindustry.com\/wp-content\/uploads\/2024\/04\/39246-LoGlobal2010-1.jpg\",\"contentUrl\":\"https:\/\/www.navarrafilmindustry.com\/wp-content\/uploads\/2024\/04\/39246-LoGlobal2010-1.jpg\",\"width\":600,\"height\":504},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.navarrafilmindustry.com\/es\/empresas-profesionales\/global-servicios-culturales\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.navarrafilmindustry.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Empresas y profesionales\",\"item\":\"https:\/\/www.navarrafilmindustry.com\/es\/empresas-profesionales\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Global Servicios Culturales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.navarrafilmindustry.com\/eu\/#website\",\"url\":\"https:\/\/www.navarrafilmindustry.com\/eu\/\",\"name\":\"NFI\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.navarrafilmindustry.com\/eu\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Global Servicios Culturales - NFI","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.navarrafilmindustry.com\/es\/empresas-profesionales\/global-servicios-culturales\/","og_locale":"es_ES","og_type":"article","og_title":"Global Servicios Culturales - NFI","og_description":"Global Servicios Culturales cuenta con una plantilla fija de 17 t\u00e9cnicos especialistas en artes esc\u00e9nicas (sonido, iluminaci\u00f3n, maquinaria&#8230;), y un amplio abanico de personal auxiliar de carga y descarga, personal de atenci\u00f3n y profesional t\u00e9cnico especialista que habitualmente trabaja para nosotros. Desde Global se realiza la busqueda del perfil indicado, su alta en la seguridad social, nominas etc Global Servicios Culturales tambi\u00e9n cuenta con un departamento de gesti\u00f3n cultural desde el que se realizan las producci\u00f3n de diferentes eventos como exposiciones en Ciudadela, Festival de danza vertical, la muralla en danza desde su primera edici\u00f3n, Festival de Teatro de Olite&#8230; Para atender todos estos eventos Global hace la producci\u00f3n y asistencia t\u00e9cnica de cualquier evento desde el trabajo de oficina hasta el personal de atenci\u00f3n al p\u00fablico.","og_url":"https:\/\/www.navarrafilmindustry.com\/es\/empresas-profesionales\/global-servicios-culturales\/","og_site_name":"NFI","article_modified_time":"2026-01-19T11:43:41+00:00","og_image":[{"width":600,"height":504,"url":"https:\/\/www.navarrafilmindustry.com\/wp-content\/uploads\/2024\/04\/39246-LoGlobal2010-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.navarrafilmindustry.com\/es\/empresas-profesionales\/global-servicios-culturales\/","url":"https:\/\/www.navarrafilmindustry.com\/es\/empresas-profesionales\/global-servicios-culturales\/","name":"Global Servicios Culturales - NFI","isPartOf":{"@id":"https:\/\/www.navarrafilmindustry.com\/eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.navarrafilmindustry.com\/es\/empresas-profesionales\/global-servicios-culturales\/#primaryimage"},"image":{"@id":"https:\/\/www.navarrafilmindustry.com\/es\/empresas-profesionales\/global-servicios-culturales\/#primaryimage"},"thumbnailUrl":"https:\/\/www.navarrafilmindustry.com\/wp-content\/uploads\/2024\/04\/39246-LoGlobal2010-1.jpg","datePublished":"2024-04-17T12:04:11+00:00","dateModified":"2026-01-19T11:43:41+00:00","breadcrumb":{"@id":"https:\/\/www.navarrafilmindustry.com\/es\/empresas-profesionales\/global-servicios-culturales\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.navarrafilmindustry.com\/es\/empresas-profesionales\/global-servicios-culturales\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.navarrafilmindustry.com\/es\/empresas-profesionales\/global-servicios-culturales\/#primaryimage","url":"https:\/\/www.navarrafilmindustry.com\/wp-content\/uploads\/2024\/04\/39246-LoGlobal2010-1.jpg","contentUrl":"https:\/\/www.navarrafilmindustry.com\/wp-content\/uploads\/2024\/04\/39246-LoGlobal2010-1.jpg","width":600,"height":504},{"@type":"BreadcrumbList","@id":"https:\/\/www.navarrafilmindustry.com\/es\/empresas-profesionales\/global-servicios-culturales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.navarrafilmindustry.com\/es\/"},{"@type":"ListItem","position":2,"name":"Empresas y profesionales","item":"https:\/\/www.navarrafilmindustry.com\/es\/empresas-profesionales\/"},{"@type":"ListItem","position":3,"name":"Global Servicios Culturales"}]},{"@type":"WebSite","@id":"https:\/\/www.navarrafilmindustry.com\/eu\/#website","url":"https:\/\/www.navarrafilmindustry.com\/eu\/","name":"NFI","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.navarrafilmindustry.com\/eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.navarrafilmindustry.com\/es\/wp-json\/wp\/v2\/empresa-profesional\/39246"}],"collection":[{"href":"https:\/\/www.navarrafilmindustry.com\/es\/wp-json\/wp\/v2\/empresa-profesional"}],"about":[{"href":"https:\/\/www.navarrafilmindustry.com\/es\/wp-json\/wp\/v2\/types\/empresa-profesional"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.navarrafilmindustry.com\/es\/wp-json\/wp\/v2\/media\/39247"}],"wp:attachment":[{"href":"https:\/\/www.navarrafilmindustry.com\/es\/wp-json\/wp\/v2\/media?parent=39246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}